{"id":17515,"date":"2016-05-19T00:00:00","date_gmt":"2016-05-19T00:00:00","guid":{"rendered":"https:\/\/cadca1stg.wpengine.com\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/"},"modified":"2016-05-19T00:00:00","modified_gmt":"2016-05-19T00:00:00","slug":"celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2","status":"publish","type":"resource","link":"https:\/\/www.cadca.org\/fr\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/","title":{"rendered":"C\u00e9l\u00e9brez vos r\u00e9ussites. Postulez maintenant pour un CADCA GOT RESULTATS 2016\u00a0! Prix de la Coalition d&#039;excellence"},"content":{"rendered":"<p>Chaque ann\u00e9e, CADCA offre aux coalitions la chance de recevoir une reconnaissance nationale pour leurs contributions \u00e0 la r\u00e9duction de la toxicomanie au niveau communautaire. Institut de la coalition nationale du CADCA, OBTENU DES R\u00c9SULTATS\u00a0! Les prix Coalition of Excellence r\u00e9compensent les coalitions qui ont mis en \u0153uvre une approche compl\u00e8te et efficace bas\u00e9e sur les donn\u00e9es pour r\u00e9soudre leurs probl\u00e8mes locaux de toxicomanie. Les candidatures doivent \u00eatre d\u00e9pos\u00e9es le vendredi 5 ao\u00fbt 2016.<\/p>\n<p>En postulant pour ce prix, votre coalition s&#039;entra\u00eenera \u00e0 pr\u00e9senter des arguments convaincants quant \u00e0 ses contributions positives \u00e0 la communaut\u00e9. Les coalitions sont invit\u00e9es \u00e0 d\u00e9velopper une pr\u00e9sentation PowerPoint racontant comment leur \u00e9valuation communautaire a contribu\u00e9 \u00e0 une compr\u00e9hension plus globale d&#039;un probl\u00e8me sp\u00e9cifique de toxicomanie et a \u00e9clair\u00e9 leur approche vers l&#039;\u00e9laboration de solutions efficaces. L&#039;accent est fortement mis sur l&#039;utilisation de donn\u00e9es et sur un processus de mod\u00e9lisation logique solide\u00a0; cette approche se traduira par un outil utile que votre coalition pourra utiliser pour communiquer vos r\u00e9sultats aux bailleurs de fonds et partenaires potentiels. Alors qu&#039;est-ce que tu attends? C\u00e9l\u00e9brez le travail r\u00e9ussi de votre communaut\u00e9 et de votre coalition et soyez reconnu.<\/p>\n<p>Il y a quelques changements dans l&#039;application cette ann\u00e9e\u00a0:<\/p>\n<ul>\n<li>Tous les candidats \u00e0 la coalition mettront en avant leurs r\u00e9ussites dans un seul domaine de la toxicomanie.<\/li>\n<li>CADCA reconna\u00eetra officiellement tous les demi-finalistes dans ce processus de candidature en deux phases.<\/li>\n<li>Les demi-finalistes et les gagnants recevront une lettre sign\u00e9e par le pr\u00e9sident-directeur g\u00e9n\u00e9ral de CADCA, Arthur T. Dean, et par la directrice du National Coalition Institute de CADCA, Kareemah Abdullah.<\/li>\n<li>Les demi-finalistes et les gagnants seront reconnus dans le cadre du CADCA.\u00a0<em>Coalitions en ligne<\/em>\u00a0Newsletter hebdomadaire.<\/li>\n<\/ul>\n<p>Les gagnants b\u00e9n\u00e9ficient de nombreux avantages suppl\u00e9mentaires, notamment une inscription et un voyage gratuits au Forum national de leadership 2017 de CADCA et la participation \u00e0 des ateliers et des webinaires, mettant en valeur les succ\u00e8s de votre coalition dans le domaine de la pr\u00e9vention de la toxicomanie.<\/p>\n<p>Une liste plus compl\u00e8te des avantages pour les demi-finalistes et les gagnants est disponible sur le site Web de CADCA, ainsi que toutes les instructions et documents de candidature n\u00e9cessaires. Veuillez visiter<a href=\"https:\/\/www.cadca.org\/fr\/blue-ribbon-coalitions\/\" target=\"_blank\" rel=\"noopener\"> www.cadca.org\/gotoutcomes<\/a>\u00a0pour plus de d\u00e9tails.<\/p>\n<p>Nous vous encourageons fortement \u00e0 contacter CADCA pour obtenir des conseils avant de commencer le processus de candidature. Veuillez appeler le 1-800-54-CADCA (1-800-542-2322), poste 23. 245 ou envoyez un e-mail \u00e0<a href=\"mailto:gotoutcomes@cadca.org\"> gotoutcomes@cadca.org<\/a>. De plus, inscrivez-vous \u00e0 un webinaire CADCA gratuit pour les candidats potentiels le mardi 8 juin, de 15 h \u00e0 16 h 30 HNE. Au cours du webinaire, nous fournirons des conseils sur la fa\u00e7on de d\u00e9velopper une application solide.<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Each year, CADCA offers coalitions the chance to receive national recognition for their contributions to community-level substance abuse reduction outcomes.<\/p>","protected":false},"author":23,"featured_media":0,"template":"","resource_type":[281],"drug_specific_issues":[],"action_to_do":[],"class_list":["post-17515","resource","type-resource","status-publish","hentry","resource_type-coalitions-online"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award | CADCA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadca.org\/fr\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award | CADCA\" \/>\n<meta property=\"og:description\" content=\"Each year, CADCA offers coalitions the chance to receive national recognition for their contributions to community-level substance abuse reduction outcomes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadca.org\/fr\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/\" \/>\n<meta property=\"og:site_name\" content=\"CADCA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/cadca-member-of-logo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\\\/\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\\\/\",\"name\":\"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award | CADCA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\"},\"datePublished\":\"2016-05-19T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadca.org\\\/resource\\\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadca.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/\",\"name\":\"CADCA\",\"description\":\"The Premier Prevention Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadca.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award | CADCA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadca.org\/fr\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award | CADCA","og_description":"Each year, CADCA offers coalitions the chance to receive national recognition for their contributions to community-level substance abuse reduction outcomes.","og_url":"https:\/\/www.cadca.org\/fr\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/","og_site_name":"CADCA","og_image":[{"width":880,"height":500,"url":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/cadca-member-of-logo1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cadca.org\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/","url":"https:\/\/www.cadca.org\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/","name":"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award | CADCA","isPartOf":{"@id":"https:\/\/www.cadca.org\/#website"},"datePublished":"2016-05-19T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.cadca.org\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadca.org\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadca.org\/resource\/celebrate-your-successes-apply-now-for-a-2016-cadca-got-outcomes-coalition-of-excellence-award-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadca.org\/"},{"@type":"ListItem","position":2,"name":"Celebrate Your Successes. Apply Now for a 2016 CADCA GOT OUTCOMES! Coalition of Excellence Award"}]},{"@type":"WebSite","@id":"https:\/\/www.cadca.org\/#website","url":"https:\/\/www.cadca.org\/","name":"CADCA","description":"The Premier Prevention Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadca.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/resource\/17515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/users\/23"}],"version-history":[{"count":0,"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/resource\/17515\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/media?parent=17515"}],"wp:term":[{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/resource_type?post=17515"},{"taxonomy":"drug_specific_issues","embeddable":true,"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/drug_specific_issues?post=17515"},{"taxonomy":"action_to_do","embeddable":true,"href":"https:\/\/www.cadca.org\/fr\/wp-json\/wp\/v2\/action_to_do?post=17515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}