{"id":17745,"date":"2015-09-03T00:00:00","date_gmt":"2015-09-03T00:00:00","guid":{"rendered":"https:\/\/cadca1stg.wpengine.com\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/"},"modified":"2015-09-03T00:00:00","modified_gmt":"2015-09-03T00:00:00","slug":"coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet","status":"publish","type":"resource","link":"https:\/\/www.cadca.org\/es\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/","title":{"rendered":"Coaliciones en acci\u00f3n: Coalici\u00f3n costarricense cubierta en importante medio de noticias en l\u00ednea"},"content":{"rendered":"<div>\n<p><em>La estrella costarricense<\/em> esta semana public\u00f3 un art\u00edculo sobre el trabajo de CADCA en ese pa\u00eds centroamericano. El art\u00edculo tambi\u00e9n fue escrito en ingl\u00e9s, lo que lo hace m\u00e1s accesible para los miembros de la coalici\u00f3n de los Estados Unidos.<\/p>\n<p>Durante varios a\u00f1os, explica la historia, la gente en el distrito de Pavas de Costa Rica experiment\u00f3 un aumento en la delincuencia y en el consumo de marihuana entre los j\u00f3venes. Pero despu\u00e9s de que se form\u00f3 una coalici\u00f3n, gracias a la capacitaci\u00f3n y asistencia de los Programas Internacionales de CADCA, los ciudadanos locales desarrollaron un proceso de planificaci\u00f3n y comenzaron a implementar estrategias de prevenci\u00f3n basadas en evidencia.<\/p>\n<p>CADCA comenz\u00f3 a trabajar en Costa Rica hace dos a\u00f1os para ayudar a los ciudadanos preocupados en Pavas a formar una coalici\u00f3n comunitaria. Ubicado dentro del \u00e1rea metropolitana de la ciudad capital de San Jos\u00e9, Pavas es el distrito m\u00e1s grande y poblado de Costa Rica.<\/p>\n<\/div>\n<p>Para ayudar a reducir el crimen en la ciudad, una de las primeras estrategias que implement\u00f3 la coalici\u00f3n fue aumentar las patrullas policiales en \u00e1reas problem\u00e1ticas clave. Un grupo de miembros de la coalici\u00f3n, encabezados por un miembro de la coalici\u00f3n que tambi\u00e9n es dentista local, se acerc\u00f3 al Ministerio de Justicia para expresar sus preocupaciones. En respuesta, el Ministerio asign\u00f3 25 polic\u00edas para patrullar los puntos cr\u00edticos en Pavas.<\/p>\n<p>La coalici\u00f3n Pavas tambi\u00e9n ha implementado varias estrategias para abordar el consumo de marihuana y alcohol entre los j\u00f3venes. Por ejemplo, aumentaron el n\u00famero de actividades recreativas y deportivas para j\u00f3venes y lanzaron iniciativas para educar a los j\u00f3venes sobre los peligros del consumo de drogas y alcohol. Estas estrategias ayudaron a desarrollar la capacidad de la coalici\u00f3n y aprovecharon los recursos para un eventual cambio en la comunidad.<\/p>\n<p>CADCA actualmente trabaja con pa\u00edses en los cinco continentes, ayud\u00e1ndolos a formar coaliciones comunitarias para abordar sus problemas locales de abuso de sustancias. Desde 2005, CADCA ha ayudado a construir m\u00e1s de 130 coaliciones comunitarias antidrogas en 22 pa\u00edses. Las actividades de reducci\u00f3n de la demanda de CADCA en Costa Rica cuentan con el apoyo de la Oficina de Cumplimiento de la Ley Internacional y Narc\u00f3ticos del Departamento de Estado de los Estados Unidos.<\/p>\n<p><strong>VER TAMBI\u00c9N:<\/strong><\/p>\n<p><a href=\"https:\/\/www.cadca.org\/es\/resources\/cadca-addresses-big-problems-brazil-more-coalition-building\/\" target=\"_blank\" rel=\"noopener\">CADCA aborda grandes problemas en Brasil mediante la creaci\u00f3n de m\u00e1s coaliciones<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>The Costa Rica Star this week published an article about CADCA\u2019s work in that Central American country. The article was<\/p>","protected":false},"author":23,"featured_media":0,"template":"","resource_type":[281],"drug_specific_issues":[],"action_to_do":[],"class_list":["post-17745","resource","type-resource","status-publish","hentry","resource_type-coalitions-online"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet | CADCA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadca.org\/es\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet | CADCA\" \/>\n<meta property=\"og:description\" content=\"The Costa Rica Star this week published an article about CADCA\u2019s work in that Central American country. The article was\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadca.org\/es\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/\" \/>\n<meta property=\"og:site_name\" content=\"CADCA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/cadca-member-of-logo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\\\/\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\\\/\",\"name\":\"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet | CADCA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\"},\"datePublished\":\"2015-09-03T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadca.org\\\/resource\\\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/resource\\\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadca.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/\",\"name\":\"CADCA\",\"description\":\"The Premier Prevention Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadca.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet | CADCA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadca.org\/es\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/","og_locale":"es_ES","og_type":"article","og_title":"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet | CADCA","og_description":"The Costa Rica Star this week published an article about CADCA\u2019s work in that Central American country. The article was","og_url":"https:\/\/www.cadca.org\/es\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/","og_site_name":"CADCA","og_image":[{"width":880,"height":500,"url":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/cadca-member-of-logo1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cadca.org\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/","url":"https:\/\/www.cadca.org\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/","name":"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet | CADCA","isPartOf":{"@id":"https:\/\/www.cadca.org\/#website"},"datePublished":"2015-09-03T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.cadca.org\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadca.org\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadca.org\/resource\/coalitions-in-action-costa-rican-coalition-covered-in-major-online-news-outlet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadca.org\/"},{"@type":"ListItem","position":2,"name":"Coalitions in Action: Costa Rican Coalition Covered in Major Online News Outlet"}]},{"@type":"WebSite","@id":"https:\/\/www.cadca.org\/#website","url":"https:\/\/www.cadca.org\/","name":"CADCA","description":"The Premier Prevention Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadca.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/resource\/17745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/types\/resource"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/users\/23"}],"version-history":[{"count":0,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/resource\/17745\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/media?parent=17745"}],"wp:term":[{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/resource_type?post=17745"},{"taxonomy":"drug_specific_issues","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/drug_specific_issues?post=17745"},{"taxonomy":"action_to_do","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/action_to_do?post=17745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}