{"id":18121,"date":"2015-03-30T00:00:00","date_gmt":"2015-03-30T00:00:00","guid":{"rendered":"https:\/\/cadca1stg.wpengine.com\/2015\/03\/30\/preventing-prescription-drug-abuse-is-possible\/"},"modified":"2024-04-24T19:52:54","modified_gmt":"2024-04-24T19:52:54","slug":"preventing-prescription-drug-abuse-possible","status":"publish","type":"post","link":"https:\/\/www.cadca.org\/es\/programs-in-action\/preventing-prescription-drug-abuse-possible\/","title":{"rendered":"Es posible prevenir el abuso de medicamentos recetados"},"content":{"rendered":"<p>Uno de mis poemas favoritos es &quot;Parando en el bosque en una noche nevada&quot; de Robert Frost. En \u00e9l, Frost habla de &quot;promesas que cumplir&quot; y nos ofrece esa frase tan citada de &quot;millas que recorrer antes de dormir&quot;. Las palabras de este ic\u00f3nico poema me vienen a la mente cuando pienso en la respuesta de nuestra naci\u00f3n a la epidemia de abuso de medicamentos recetados.<\/p>\n<p>Desde la epidemia de crack de la d\u00e9cada de 1980, no hay ning\u00fan problema relacionado con las drogas que haya cautivado m\u00e1s a la naci\u00f3n que el abuso de medicamentos recetados, y con raz\u00f3n. Lamentablemente, hoy en d\u00eda, el abuso de medicamentos recetados representa una de las mayores epidemias de salud p\u00fablica de nuestro tiempo. La adicci\u00f3n a los opioides contin\u00faa destruyendo miles de vidas y devastando comunidades.<\/p>\n<p>De acuerdo con la <a href=\"https:\/\/www.drugabuse.gov\/publications\/research-reports\/prescription-drugs\/director\">Instituto Nacional sobre el Abuso de Drogas<\/a>, se estima que 52 millones de personas (20 por ciento de las personas de 12 a\u00f1os o m\u00e1s) han abusado o hecho mal uso de medicamentos recetados al menos una vez en su vida. Las exposiciones a productos farmac\u00e9uticos representan alrededor de 40% de llamadas a centros de toxicolog\u00eda para ni\u00f1os de 6 a\u00f1os y menos. adem\u00e1s, el <a href=\"https:\/\/www.cdc.gov\/\">Centros de Control y Prevenci\u00f3n de Enfermedades<\/a> Se estima que cada d\u00eda mueren 120 personas como resultado de sobredosis de drogas, muchas de ellas atribuidas a analg\u00e9sicos recetados.<\/p>\n<p>Nosotros, colectivamente, como comunidad de salud p\u00fablica, hemos <em>promesas de mantener<\/em> \u2013a las familias y comunidades estadounidenses que est\u00e1n en crisis.<\/p>\n<p>CADCA apoya un enfoque integral para abordar la epidemia de abuso de medicamentos recetados que abarca la prevenci\u00f3n, el tratamiento y la recuperaci\u00f3n. Por ejemplo, apoyamos la ampliaci\u00f3n de los programas de vigilancia de medicamentos recetados (PDMP), la mejora de la capacitaci\u00f3n m\u00e9dica en la prescripci\u00f3n adecuada de potentes analg\u00e9sicos recetados, la exigencia de que los fabricantes de medicamentos creen formulaciones disuasorias del abuso, la ampliaci\u00f3n espectacular de las opciones de tratamiento para los adictos a los opioides y el aumento del acceso a los Medicamento para revertir una sobredosis de naloxona.<\/p>\n<p>Y creemos sinceramente que podemos prevenir este problema antes de que comience. Si bien es importante solucionar el enorme problema que tenemos actualmente y salvar a las personas de una sobredosis, es posible evitar que los j\u00f3venes abusen de los medicamentos recetados.<\/p>\n<p>\u00bfPor qu\u00e9 creemos en la prevenci\u00f3n? Porque <em>SABEMOS<\/em> funciona. Las coaliciones comunitarias, en particular las financiadas por el <a href=\"https:\/\/www.whitehouse.gov\/ondcp\/\">Programa Comunidades Libres de Drogas<\/a>, han demostrado una y otra vez que pueden prevenir y reducir el consumo de drogas entre los j\u00f3venes. Tomemos simplemente el ejemplo de la Coalici\u00f3n Libre de Drogas del Condado de Carter, que redujo el uso no m\u00e9dico de medicamentos recetados entre 10<sup>el<\/sup> y 12<sup>el<\/sup> estudiantes en m\u00e1s del 80 por ciento.<\/p>\n<p>Y el n\u00famero de j\u00f3venes que abusan de los medicamentos recetados ha ido disminuyendo en los \u00faltimos a\u00f1os. Por ejemplo, la encuesta m\u00e1s reciente Monitoring the Future mostr\u00f3 que menos estudiantes de 12\u00ba grado abusan de medicamentos recetados, cayendo del 16 por ciento en 2013 al 14 por ciento en 2014. En 2005, el 17 por ciento indic\u00f3 un uso indebido de alg\u00fan medicamento recetado. Esto es progreso.<\/p>\n<p>Las coaliciones han contribuido a ese declive. Las coaliciones son el veh\u00edculo de prevenci\u00f3n m\u00e1s eficaz de nuestra naci\u00f3n porque utilizan un enfoque integral basado en datos que se dirige no solo a los j\u00f3venes, sino tambi\u00e9n a los padres, maestros, proveedores de atenci\u00f3n m\u00e9dica, autoridades policiales y otros sectores clave de una comunidad. Las coaliciones abordan las condiciones locales del abuso de medicamentos con un enfoque de salud p\u00fablica que analiza todas las facetas de la condici\u00f3n humana, desde nuestra gen\u00e9tica y vida familiar hasta nuestras escuelas, sistemas y leyes.<\/p>\n<p>Si fuera por m\u00ed, cada comunidad de Estados Unidos tendr\u00eda una coalici\u00f3n de prevenci\u00f3n activa.<\/p>\n<p>Como mam\u00e1, quiero que mi hijo crezca en un ambiente seguro, saludable y libre de drogas. No hace mucho, pas\u00e9 varias horas un viernes por la tarde hablando sobre soluciones en materia de pol\u00edticas de drogas con un alto funcionario inteligente del gobierno. Es miembro de una coalici\u00f3n local de miembros de CADCA y resulta que tambi\u00e9n es un hombre que recientemente perdi\u00f3 a su hijo por abuso de medicamentos recetados. D\u00e9jame decirte que esa noche abrac\u00e9 a mi hijo un poco m\u00e1s de lo habitual.<\/p>\n<p>Hoy en d\u00eda, 120 familias han perdido a sus hijos, ya sean ni\u00f1os peque\u00f1os, adolescentes o adultos, para siempre. Podemos ayudar a reducir estas tragedias y todo comienza con la prevenci\u00f3n. Pero todos sabemos que tenemos <em>Kil\u00f3metros por recorrer antes de dormir. <\/em><\/p>\n<p>Si a\u00fan no eres parte de CADCA, espero que te tomes un momento y <a href=\"https:\/\/www.cadca.org\/es\/membership\/\">unirse al movimiento de coalici\u00f3n.<\/a> Ay\u00fadanos a poner fin a esta epidemia.<\/p>\n<p><em>Mary Elizabeth Elliott es una madre apasionada y vicepresidenta de Comunicaciones, Membres\u00eda y TI de CADCA. Ella llevar\u00e1 a cabo una capacitaci\u00f3n sobre prevenci\u00f3n del abuso de medicamentos recetados en el <\/em><em>Cumbre Nacional sobre Abuso de Drogas Recetadas<\/em><em> en Atlanta. Puede ser contactada en <\/em><a href=\"mailto:melliott@cadca.org\"><em>melliott@cadca.org<\/em><\/a><em>.\u00a0<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Uno de mis poemas favoritos es &quot;Parando en el bosque en una noche nevada&quot; de Robert Frost. En \u00e9l, Frost habla de<\/p>","protected":false},"author":23,"featured_media":2423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[362],"tags":[228,221,227],"class_list":["post-18121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programs-in-action","tag-medicine-abuse","tag-opioids","tag-prescription-drug-abuse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preventing Prescription Drug Abuse Is Possible | CADCA<\/title>\n<meta name=\"description\" content=\"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadca.org\/es\/programs-in-action\/preventing-prescription-drug-abuse-possible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preventing Prescription Drug Abuse Is Possible | CADCA\" \/>\n<meta property=\"og:description\" content=\"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadca.org\/es\/programs-in-action\/preventing-prescription-drug-abuse-possible\/\" \/>\n<meta property=\"og:site_name\" content=\"CADCA\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-30T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T19:52:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/mel_and_larse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marianne Varkiani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marianne Varkiani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/\"},\"author\":{\"name\":\"Marianne Varkiani\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#\\\/schema\\\/person\\\/93495eb4b8a7735542982cd2b7f617fd\"},\"headline\":\"Preventing Prescription Drug Abuse Is Possible\",\"datePublished\":\"2015-03-30T00:00:00+00:00\",\"dateModified\":\"2024-04-24T19:52:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/\"},\"wordCount\":722,\"image\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/mel_and_larse.jpg\",\"keywords\":[\"medicine abuse\",\"opioids\",\"prescription drug abuse\"],\"articleSection\":[\"Programs in Action\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/\",\"name\":\"Preventing Prescription Drug Abuse Is Possible | CADCA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/mel_and_larse.jpg\",\"datePublished\":\"2015-03-30T00:00:00+00:00\",\"dateModified\":\"2024-04-24T19:52:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#\\\/schema\\\/person\\\/93495eb4b8a7735542982cd2b7f617fd\"},\"description\":\"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/mel_and_larse.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/mel_and_larse.jpg\",\"width\":275,\"height\":269},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/programs-in-action\\\/preventing-prescription-drug-abuse-possible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadca.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preventing Prescription Drug Abuse Is Possible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/\",\"name\":\"CADCA\",\"description\":\"The Premier Prevention Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadca.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#\\\/schema\\\/person\\\/93495eb4b8a7735542982cd2b7f617fd\",\"name\":\"Marianne Varkiani\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preventing Prescription Drug Abuse Is Possible | CADCA","description":"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadca.org\/es\/programs-in-action\/preventing-prescription-drug-abuse-possible\/","og_locale":"es_ES","og_type":"article","og_title":"Preventing Prescription Drug Abuse Is Possible | CADCA","og_description":"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others","og_url":"https:\/\/www.cadca.org\/es\/programs-in-action\/preventing-prescription-drug-abuse-possible\/","og_site_name":"CADCA","article_published_time":"2015-03-30T00:00:00+00:00","article_modified_time":"2024-04-24T19:52:54+00:00","og_image":[{"width":275,"height":269,"url":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/mel_and_larse.jpg","type":"image\/jpeg"}],"author":"Marianne Varkiani","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marianne Varkiani","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#article","isPartOf":{"@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/"},"author":{"name":"Marianne Varkiani","@id":"https:\/\/www.cadca.org\/#\/schema\/person\/93495eb4b8a7735542982cd2b7f617fd"},"headline":"Preventing Prescription Drug Abuse Is Possible","datePublished":"2015-03-30T00:00:00+00:00","dateModified":"2024-04-24T19:52:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/"},"wordCount":722,"image":{"@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/mel_and_larse.jpg","keywords":["medicine abuse","opioids","prescription drug abuse"],"articleSection":["Programs in Action"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/","url":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/","name":"Preventing Prescription Drug Abuse Is Possible | CADCA","isPartOf":{"@id":"https:\/\/www.cadca.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#primaryimage"},"image":{"@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/mel_and_larse.jpg","datePublished":"2015-03-30T00:00:00+00:00","dateModified":"2024-04-24T19:52:54+00:00","author":{"@id":"https:\/\/www.cadca.org\/#\/schema\/person\/93495eb4b8a7735542982cd2b7f617fd"},"description":"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others","breadcrumb":{"@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#primaryimage","url":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/mel_and_larse.jpg","contentUrl":"https:\/\/www.cadca.org\/wp-content\/uploads\/2022\/03\/mel_and_larse.jpg","width":275,"height":269},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadca.org\/programs-in-action\/preventing-prescription-drug-abuse-possible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadca.org\/"},{"@type":"ListItem","position":2,"name":"Preventing Prescription Drug Abuse Is Possible"}]},{"@type":"WebSite","@id":"https:\/\/www.cadca.org\/#website","url":"https:\/\/www.cadca.org\/","name":"CADCA","description":"The Premier Prevention Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadca.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cadca.org\/#\/schema\/person\/93495eb4b8a7735542982cd2b7f617fd","name":"Marianne Varkiani"}]}},"_links":{"self":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/posts\/18121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/comments?post=18121"}],"version-history":[{"count":0,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/posts\/18121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/media\/2423"}],"wp:attachment":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/media?parent=18121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/categories?post=18121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/tags?post=18121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}