{"id":18018,"date":"2022-06-16T00:00:00","date_gmt":"2022-06-16T00:00:00","guid":{"rendered":"https:\/\/cadca1stg.wpengine.com\/2022\/06\/16\/youth-spotlight-jabeen-sheikh\/"},"modified":"2024-04-24T15:42:47","modified_gmt":"2024-04-24T15:42:47","slug":"youth-spotlight-jabeen-sheikh","status":"publish","type":"post","link":"https:\/\/www.cadca.org\/es\/youth\/youth-spotlight-jabeen-sheikh\/","title":{"rendered":"J\u00f3venes destacados: Jabeen Sheikh"},"content":{"rendered":"<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\"><strong>Jeque Jabeen<\/strong>, miembro del Consejo de Liderazgo Juvenil para Comunidades en Crisis (CIC) y el Consejo Asesor Nacional de J\u00f3venes (NYAC) de CADCA, se graduar\u00e1 de Ridge High School este junio y en 2023 se transferir\u00e1 a la Universidad de Cornell en la pista de pre-medicina.<\/span><\/span><\/p>\n<div class=\"OutlineElement Ltr SCXW14379844 BCX8\" style=\"margin: 0px; padding: 0px; user-select: text; -webkit-user-drag: none; -webkit-tap-highlight-color: transparent; overflow: visible; cursor: text; clear: both; position: relative; direction: ltr; color: rgb(0, 0, 0); font-family: \"segoe ui\", \"segoe ui web\", arial, verdana, sans-serif; font-size: 12px;\">\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">Jabeen se uni\u00f3 a CIC, una coalici\u00f3n con sede en Bernadsville, Nueva Jersey, durante su segundo a\u00f1o de secundaria. \u201cOriginalmente me un\u00ed porque necesitaba horas de voluntariado y, casualmente, eso fue en la \u00e9poca en que formaron su Consejo de Liderazgo Juvenil. Me convert\u00ed en uno de los primeros en unirme, junto con algunos otros estudiantes de otras escuelas secundarias en el \u00e1rea, \u00a1y termin\u00e9 amando todo lo que hicimos y hemos estado haciendo!<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">\u201cCreo que una de mis iniciativas favoritas fue durante mi primer a\u00f1o de secundaria, en el punto \u00e1lgido de la pandemia. Creamos una campa\u00f1a llamada &#039;Liderar con amor&#039; donde hicimos peque\u00f1as bolsas de regalo que inclu\u00edan recursos de salud mental y citas positivas que se entregaron a amigos, equipos deportivos en la escuela y miembros de la familia. El punto era disminuir los sentimientos de soledad durante ese momento colectivamente dif\u00edcil y hacer que la gente siguiera pasando las bolsas. Hicimos un seguimiento de nuestro impacto utilizando c\u00f3digos QR, por lo que cada vez que alguien nuevo escaneaba el c\u00f3digo en la bolsa, pod\u00edamos contar a cu\u00e1ntas personas llegamos\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">\u201cFinalmente, terminamos presentando &#039;Lead with Love&#039; a SAMHSA, y les gust\u00f3 mucho. Implementaron la campa\u00f1a en otras escuelas y se distribuyeron cerca de 400 bolsas en todo Nueva Jersey, por lo que nos sentimos orgullosos de ese impacto\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">\u201cAhora estamos trabajando en una campa\u00f1a en las redes sociales llamada &#039;One Clear Path&#039;, que se enfoca en brindar a los j\u00f3venes ejemplos de alternativas al uso de sustancias. Hicimos videos en Instagram y TikTok donde muestro lo que hacemos mis amigos y yo para divertirnos en lugar de beber los viernes por la noche y, hasta ahora, hemos recibido muchos comentarios positivos\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">\u201cSer parte de esta coalici\u00f3n ha sido una excelente manera de involucrarme con mi comunidad y hacer algo impactante. Amo a mis l\u00edderes adultos y a los otros j\u00f3venes que son parte de esto. No son solo los adultos que nos dicen que no consumamos drogas o no bebamos: es un momento divertido y podemos tener conversaciones abiertas. He aprendido mucho sobre diferentes perspectivas sobre el uso de sustancias y la prevenci\u00f3n del abuso\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">Despu\u00e9s de que los l\u00edderes adultos de Jabeen supieran sobre NYAC, la alentaron enf\u00e1ticamente a postularse para fortalecer a\u00fan m\u00e1s sus habilidades de liderazgo y conocer a j\u00f3venes con ideas afines en todo el pa\u00eds. \u201cUnirme a NYAC ha sido una oportunidad realmente maravillosa para conocer a otros estudiantes de secundaria de diferentes \u00e1reas y or\u00edgenes, pero todos con un objetivo similar. Actualmente apenas est\u00e1 despegando, pero tengo muchas ganas de asistir a la mitad de a\u00f1o este julio para conocer a los otros miembros en persona y aprender m\u00e1s sobre la prevenci\u00f3n\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:arial,helvetica,sans-serif;\">Durante el primer a\u00f1o de universidad de Jabeen, planea mantenerse conectada con su coalici\u00f3n y apoyar a la pr\u00f3xima generaci\u00f3n de estudiantes de primer a\u00f1o en CIC. Adem\u00e1s, continuar\u00e1 trabajando con NYAC como una voz para la juventud. \u201cCreo que mi participaci\u00f3n en la prevenci\u00f3n realmente hizo que me interesara la salud p\u00fablica y, en general, c\u00f3mo mejorar la salud de las comunidades. Siempre supe que quer\u00eda estudiar medicina pero trabajar en prevenci\u00f3n ha sido una inspiraci\u00f3n por el impacto que puedes tener en la vida de otras personas. Espero ver lo que traer\u00e1n los pr\u00f3ximos pasos de este viaje\u201d.<\/span><\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Jabeen Sheikh, miembro del Consejo de Liderazgo Juvenil para Comunidades en Crisis (CIC) y del Consejo Asesor Nacional de J\u00f3venes (NYAC) de CADCA,<\/p>","protected":false},"author":23,"featured_media":18019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[359],"tags":[],"class_list":["post-18018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-youth"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Youth Spotlight: Jabeen Sheikh | CADCA<\/title>\n<meta name=\"description\" content=\"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadca.org\/es\/youth\/youth-spotlight-jabeen-sheikh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Youth Spotlight: Jabeen Sheikh | CADCA\" \/>\n<meta property=\"og:description\" content=\"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadca.org\/es\/youth\/youth-spotlight-jabeen-sheikh\/\" \/>\n<meta property=\"og:site_name\" content=\"CADCA\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-16T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T15:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadca.org\/wp-content\/uploads\/2023\/05\/youthspotlight-jabeen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marianne Varkiani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marianne Varkiani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/\"},\"author\":{\"name\":\"Marianne Varkiani\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#\\\/schema\\\/person\\\/93495eb4b8a7735542982cd2b7f617fd\"},\"headline\":\"Youth Spotlight: Jabeen Sheikh\",\"datePublished\":\"2022-06-16T00:00:00+00:00\",\"dateModified\":\"2024-04-24T15:42:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/\"},\"wordCount\":586,\"image\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/youthspotlight-jabeen.png\",\"articleSection\":[\"Youth\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/\",\"name\":\"Youth Spotlight: Jabeen Sheikh | CADCA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/youthspotlight-jabeen.png\",\"datePublished\":\"2022-06-16T00:00:00+00:00\",\"dateModified\":\"2024-04-24T15:42:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#\\\/schema\\\/person\\\/93495eb4b8a7735542982cd2b7f617fd\"},\"description\":\"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/youthspotlight-jabeen.png\",\"contentUrl\":\"https:\\\/\\\/www.cadca.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/youthspotlight-jabeen.png\",\"width\":650,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/youth\\\/youth-spotlight-jabeen-sheikh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadca.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Youth Spotlight: Jabeen Sheikh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#website\",\"url\":\"https:\\\/\\\/www.cadca.org\\\/\",\"name\":\"CADCA\",\"description\":\"The Premier Prevention Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadca.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cadca.org\\\/#\\\/schema\\\/person\\\/93495eb4b8a7735542982cd2b7f617fd\",\"name\":\"Marianne Varkiani\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Youth Spotlight: Jabeen Sheikh | CADCA","description":"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadca.org\/es\/youth\/youth-spotlight-jabeen-sheikh\/","og_locale":"es_ES","og_type":"article","og_title":"Youth Spotlight: Jabeen Sheikh | CADCA","og_description":"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others","og_url":"https:\/\/www.cadca.org\/es\/youth\/youth-spotlight-jabeen-sheikh\/","og_site_name":"CADCA","article_published_time":"2022-06-16T00:00:00+00:00","article_modified_time":"2024-04-24T15:42:47+00:00","og_image":[{"width":650,"height":300,"url":"https:\/\/www.cadca.org\/wp-content\/uploads\/2023\/05\/youthspotlight-jabeen.png","type":"image\/png"}],"author":"Marianne Varkiani","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marianne Varkiani","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#article","isPartOf":{"@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/"},"author":{"name":"Marianne Varkiani","@id":"https:\/\/www.cadca.org\/#\/schema\/person\/93495eb4b8a7735542982cd2b7f617fd"},"headline":"Youth Spotlight: Jabeen Sheikh","datePublished":"2022-06-16T00:00:00+00:00","dateModified":"2024-04-24T15:42:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/"},"wordCount":586,"image":{"@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cadca.org\/wp-content\/uploads\/2023\/05\/youthspotlight-jabeen.png","articleSection":["Youth"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/","url":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/","name":"Youth Spotlight: Jabeen Sheikh | CADCA","isPartOf":{"@id":"https:\/\/www.cadca.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#primaryimage"},"image":{"@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cadca.org\/wp-content\/uploads\/2023\/05\/youthspotlight-jabeen.png","datePublished":"2022-06-16T00:00:00+00:00","dateModified":"2024-04-24T15:42:47+00:00","author":{"@id":"https:\/\/www.cadca.org\/#\/schema\/person\/93495eb4b8a7735542982cd2b7f617fd"},"description":"CADCA represents over 5,000 community coalitions that involve individuals from key sectors including schools, law enforcement, youth, parents, healthcare, media, tribal communities and others","breadcrumb":{"@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#primaryimage","url":"https:\/\/www.cadca.org\/wp-content\/uploads\/2023\/05\/youthspotlight-jabeen.png","contentUrl":"https:\/\/www.cadca.org\/wp-content\/uploads\/2023\/05\/youthspotlight-jabeen.png","width":650,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadca.org\/youth\/youth-spotlight-jabeen-sheikh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadca.org\/"},{"@type":"ListItem","position":2,"name":"Youth Spotlight: Jabeen Sheikh"}]},{"@type":"WebSite","@id":"https:\/\/www.cadca.org\/#website","url":"https:\/\/www.cadca.org\/","name":"CADCA","description":"The Premier Prevention Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadca.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cadca.org\/#\/schema\/person\/93495eb4b8a7735542982cd2b7f617fd","name":"Marianne Varkiani"}]}},"_links":{"self":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/posts\/18018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/comments?post=18018"}],"version-history":[{"count":0,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/posts\/18018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/media\/18019"}],"wp:attachment":[{"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/media?parent=18018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/categories?post=18018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadca.org\/es\/wp-json\/wp\/v2\/tags?post=18018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}